{"id":35,"date":"2016-10-12T09:07:19","date_gmt":"2016-10-12T09:07:19","guid":{"rendered":"http:\/\/aplasteraday.com\/?p=35"},"modified":"2018-03-03T16:27:12","modified_gmt":"2018-03-03T16:27:12","slug":"35","status":"publish","type":"post","link":"https:\/\/aplasteraday.com\/es\/2016\/10\/12\/35\/","title":{"rendered":"Una idea: Granja en la cesta"},"content":{"rendered":"<p>Primer proyecto:<\/p>\n<p>Mi primera idea, que me gustar\u00eda compartir con vosotros es; \u00abGranja en la cesta\u00bb<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-20 alignright\" src=\"https:\/\/aplasteraday.com\/wp-content\/uploads\/2016\/10\/photo-1454579943364-13b2d508c27a-300x200.jpeg\" alt=\"photo-1454579943364-13b2d508c27a\" width=\"339\" height=\"226\" \/>Granja en la cesta, es un proyecto que quisiera realizar en diferentes escuelas en Basilea (Suiza). Naturalmente me gustar\u00eda tambi\u00e9n animar otros pa\u00edses y ciudades a hacer lo mismo. La idea consiste en que comida que se planta en la regi\u00f3n, se plantar\u00eda en cestas encima del campo de la escuela. Se utilizar\u00edan cestas con una pantalla-smart donde los ni\u00f1os podr\u00edan ver el agua y los otros nutrientes que la planta necesita para crecer.<\/p>\n<p>La raz\u00f3n principal porque quiero realizar este proyecto en escuelas es porque pienso que muchos padres ya no tienen tiempo de ense\u00f1ar a sus hijos de donde viene la comida que comen. Es importante de que los ni\u00f1os sepan que la verdura y fruta no crece en el supermercado. Igual de importante es, que si los ni\u00f1os ven en que temporada crecen las plantas y lo que existe en la regi\u00f3n en la que viven, se dan cuenta de la distancia que su comida tiene que recorrer hasta encontrarse encima del plato.<\/p>\n<p style=\"text-align: left;\">Me gustar\u00eda empezar solo en una escuela para ver si encontrar\u00eda patrocinadores que apoyaran esta idea. Una hora escolar m\u00e1s a la semana, seria genial para que los ni\u00f1os pudieran ver el trabajo que se necesita para crecer la comida, hasta poderla vender\/comprar.<\/p>\n<p style=\"text-align: left;\">Con la comida recogida se pudiera cocinar juntos, donar la comida para gente pobre (para los refugiados) o se pudiera vender sobre un mercado semanal.<\/p>\n<p style=\"text-align: left;\">Mi idea a\u00fan no esta terminada de pensar, pero para mi es importante de compartir mis pensamientos para hacerles crecer. Yo intentare perseguir est\u00e1 idea y tal vez mi proximo blog-post, hara ver el progresso \ud83d\ude42<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Primer proyecto: Mi primera idea, que me gustar\u00eda compartir con vosotros es; \u00abGranja en la cesta\u00bb Granja en la cesta, es un proyecto que quisiera realizar en diferentes escuelas en Basilea (Suiza). Naturalmente me gustar\u00eda tambi\u00e9n animar otros pa\u00edses y ciudades a hacer lo mismo. La idea consiste en que comida que se planta en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":242,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-35","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ideen"],"_links":{"self":[{"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/posts\/35","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/comments?post=35"}],"version-history":[{"count":7,"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/posts\/35\/revisions"}],"predecessor-version":[{"id":243,"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/posts\/35\/revisions\/243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/media\/242"}],"wp:attachment":[{"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/media?parent=35"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/categories?post=35"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aplasteraday.com\/es\/wp-json\/wp\/v2\/tags?post=35"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}